{"id":61,"date":"2020-04-13T12:24:21","date_gmt":"2020-04-13T12:24:21","guid":{"rendered":"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/?page_id=61"},"modified":"2020-07-30T06:18:04","modified_gmt":"2020-07-30T06:18:04","slug":"histroy","status":"publish","type":"page","link":"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/what-is-bladder-pain-syndrome-bps\/histroy\/","title":{"rendered":"Histroy"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":52,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-histroy.php","meta":{"footnotes":""},"class_list":["post-61","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Histroy - Healthcare professional<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/what-is-bladder-pain-syndrome-bps\/histroy\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Histroy - Healthcare professional\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/what-is-bladder-pain-syndrome-bps\/histroy\/\" \/>\n<meta property=\"og:site_name\" content=\"Healthcare professional\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-30T06:18:04+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/what-is-bladder-pain-syndrome-bps\/histroy\/\",\"url\":\"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/what-is-bladder-pain-syndrome-bps\/histroy\/\",\"name\":\"Histroy - Healthcare professional\",\"isPartOf\":{\"@id\":\"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/#website\"},\"datePublished\":\"2020-04-13T12:24:21+00:00\",\"dateModified\":\"2020-07-30T06:18:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/what-is-bladder-pain-syndrome-bps\/histroy\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/what-is-bladder-pain-syndrome-bps\/histroy\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/what-is-bladder-pain-syndrome-bps\/histroy\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"What is Bladder Pain Syndrome (BPS)?\",\"item\":\"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/what-is-bladder-pain-syndrome-bps\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Histroy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/#website\",\"url\":\"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/\",\"name\":\"Healthcare professional\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/#organization\",\"name\":\"Healthcare professional\",\"url\":\"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/wp-content\/uploads\/sites\/2\/2020\/04\/logo.png\",\"contentUrl\":\"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/wp-content\/uploads\/sites\/2\/2020\/04\/logo.png\",\"width\":198,\"height\":54,\"caption\":\"Healthcare professional\"},\"image\":{\"@id\":\"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Histroy - Healthcare professional","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/what-is-bladder-pain-syndrome-bps\/histroy\/","og_locale":"en_US","og_type":"article","og_title":"Histroy - Healthcare professional","og_url":"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/what-is-bladder-pain-syndrome-bps\/histroy\/","og_site_name":"Healthcare professional","article_modified_time":"2020-07-30T06:18:04+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/what-is-bladder-pain-syndrome-bps\/histroy\/","url":"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/what-is-bladder-pain-syndrome-bps\/histroy\/","name":"Histroy - Healthcare professional","isPartOf":{"@id":"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/#website"},"datePublished":"2020-04-13T12:24:21+00:00","dateModified":"2020-07-30T06:18:04+00:00","breadcrumb":{"@id":"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/what-is-bladder-pain-syndrome-bps\/histroy\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bladderpain.co.uk\/healthcare-professional\/what-is-bladder-pain-syndrome-bps\/histroy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/what-is-bladder-pain-syndrome-bps\/histroy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/"},{"@type":"ListItem","position":2,"name":"What is Bladder Pain Syndrome (BPS)?","item":"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/what-is-bladder-pain-syndrome-bps\/"},{"@type":"ListItem","position":3,"name":"Histroy"}]},{"@type":"WebSite","@id":"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/#website","url":"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/","name":"Healthcare professional","description":"","publisher":{"@id":"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/#organization","name":"Healthcare professional","url":"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/#\/schema\/logo\/image\/","url":"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/wp-content\/uploads\/sites\/2\/2020\/04\/logo.png","contentUrl":"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/wp-content\/uploads\/sites\/2\/2020\/04\/logo.png","width":198,"height":54,"caption":"Healthcare professional"},"image":{"@id":"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/wp-json\/wp\/v2\/pages\/61","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/wp-json\/wp\/v2\/comments?post=61"}],"version-history":[{"count":9,"href":"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/wp-json\/wp\/v2\/pages\/61\/revisions"}],"predecessor-version":[{"id":872,"href":"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/wp-json\/wp\/v2\/pages\/61\/revisions\/872"}],"up":[{"embeddable":true,"href":"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/wp-json\/wp\/v2\/pages\/52"}],"wp:attachment":[{"href":"https:\/\/www.bladderpain.co.uk\/healthcare-professional\/wp-json\/wp\/v2\/media?parent=61"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}